{"id":14,"date":"2016-06-29T10:19:22","date_gmt":"2016-06-29T08:19:22","guid":{"rendered":"https:\/\/learninglab.ensma.fr\/?p=14"},"modified":"2025-11-04T15:18:20","modified_gmt":"2025-11-04T14:18:20","slug":"pourquoi-ces-changements-de-pratiques","status":"publish","type":"post","link":"https:\/\/learninglab.ensma.fr\/index.php\/2016\/06\/29\/pourquoi-ces-changements-de-pratiques\/","title":{"rendered":"Pourquoi ces changements de pratiques"},"content":{"rendered":"<p style=\"text-align: justify;\">A travers cette vid\u00e9o d&rsquo;un dizaine de minutes, comprenez les \u00e9l\u00e8ves d&rsquo;aujourd&rsquo;hui et les \u00e9volutions p\u00e9dagogiques qui en d\u00e9coulent.<\/p>\n<p style=\"text-align: justify;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/e1LRrVYb8IE\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A travers cette vid\u00e9o d&rsquo;un dizaine de minutes, comprenez les \u00e9l\u00e8ves d&rsquo;aujourd&rsquo;hui et les \u00e9volutions p\u00e9dagogiques qui en d\u00e9coulent.<\/p>\n","protected":false},"author":2,"featured_media":268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[3,4],"tags":[],"class_list":["post-14","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-blog-learninglab","category-pedagogie","post_format-post-format-video"],"_links":{"self":[{"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/posts\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":1,"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/posts\/14\/revisions"}],"predecessor-version":[{"id":15,"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/posts\/14\/revisions\/15"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/media\/268"}],"wp:attachment":[{"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/media?parent=14"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/categories?post=14"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/learninglab.ensma.fr\/index.php\/wp-json\/wp\/v2\/tags?post=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}